{"id":1658,"date":"2024-04-25T18:08:41","date_gmt":"2024-04-25T16:08:41","guid":{"rendered":"https:\/\/clinicaoriolcanto.com\/ortodoncia\/"},"modified":"2024-05-30T19:14:57","modified_gmt":"2024-05-30T17:14:57","slug":"ortodoncia","status":"publish","type":"page","link":"https:\/\/clinicaoriolcanto.com\/es\/ortodoncia\/","title":{"rendered":"Ortodoncia con brackets y alineadores transparentes"},"content":{"rendered":"\n<div class=\"wp-block-nk-awb nk-awb alignfull nk-awb-fullheight nk-awb-content-valign-center header header--home\"><div class=\"nk-awb-wrap\" style=\"background:#0085ce\" data-awb-type=\"image\" data-awb-image-background-size=\"cover\" data-awb-image-background-position=\"50% 50%\" data-awb-mouse-parallax=\"true\" data-awb-mouse-parallax-size=\"100\" data-awb-mouse-parallax-speed=\"10000\"><div class=\"nk-awb-inner\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia.webp\" class=\"wp-image-94 jarallax-img\" alt=\"Header ortod\u00f2ncia\" width=\"3200\" height=\"2016\" srcset=\"https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia.webp 3200w, https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia-500x315.webp 500w, https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia-800x504.webp 800w, https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia-1280x806.webp 1280w, https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia-1920x1210.webp 1920w, https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia-1200x756.webp 1200w, https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia-1400x882.webp 1400w, https:\/\/clinicaoriolcanto.com\/wp-content\/uploads\/2024\/04\/header-ortodoncia-300x189.webp 300w\" sizes=\"auto, (max-width: 3200px) 100vw, 3200px\" \/><\/div><\/div><div class=\"nk-awb-wrap-content is-layout-constrained wp-block-nk-awb-is-layout-constrained\"><style>.kb-row-layout-id1658_02db4f-a3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1658_02db4f-a3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1658_02db4f-a3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1658_02db4f-a3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1658_02db4f-a3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1658_02db4f-a3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1658_02db4f-a3 alignnone container wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1658_e8216b-cf > .kt-inside-inner-col,.kadence-column1658_e8216b-cf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1658_e8216b-cf > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1658_e8216b-cf > .kt-inside-inner-col{flex-direction:column;}.kadence-column1658_e8216b-cf > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1658_e8216b-cf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1658_e8216b-cf{position:relative;}@media all and (max-width: 1024px){.kadence-column1658_e8216b-cf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1658_e8216b-cf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1658_e8216b-cf\"><div class=\"kt-inside-inner-col\"><h1 class=\"has-text-align-center has-link-color wp-elements-5c15f29beec0071bb8fddc48a7dd2909 wp-block-post-title has-text-color has-white-color\">Ortodoncia con brackets y alineadores transparentes<\/h1>\n\n\n<div class=\"container breadcrumb\"><div class=\"header-line\"><\/div><p><a href=\"https:\/\/clinicaoriolcanto.com\/es\/tratamientos\/\">Tratamientos<\/a><\/p><div class=\"header-line\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1658_863966-cf, .wp-block-kadence-advancedheading.kt-adv-heading1658_863966-cf[data-kb-block=\"kb-adv-heading1658_863966-cf\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1658_863966-cf mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1658_863966-cf[data-kb-block=\"kb-adv-heading1658_863966-cf\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1658_863966-cf img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1658_863966-cf[data-kb-block=\"kb-adv-heading1658_863966-cf\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1658_863966-cf h5 wp-block-kadence-advancedheading has-white-color has-text-color\" data-kb-block=\"kb-adv-heading1658_863966-cf\">Soluciones de ortodoncia con brackets met\u00e1licos, transparentes o alineadores para una mejor sonrisa y una higiene dental optimizada.<\/h2>\n\n\n\n<div class=\"wp-block-buttons botons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button boto--header anchor\"><a class=\"wp-block-button__link wp-element-button\" href=\"#info\">M\u00e1s informaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kb-row-layout-id1658_2b2045-f3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1658_2b2045-f3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1658_2b2045-f3 > .kt-row-column-wrap{column-gap:140px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id1658_2b2045-f3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1658_2b2045-f3 > .kt-row-column-wrap{column-gap:35px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1658_2b2045-f3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1658_2b2045-f3 alignnone fila--estatic tractament wp-block-kadence-rowlayout\" id=\"info\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-equal kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1658_78f57b-1c > .kt-inside-inner-col,.kadence-column1658_78f57b-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1658_78f57b-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1658_78f57b-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1658_78f57b-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1658_78f57b-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1658_78f57b-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column1658_78f57b-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1658_78f57b-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1658_78f57b-1c columna--text\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1658_6d98d7-b0, .wp-block-kadence-advancedheading.kt-adv-heading1658_6d98d7-b0[data-kb-block=\"kb-adv-heading1658_6d98d7-b0\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1658_6d98d7-b0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1658_6d98d7-b0[data-kb-block=\"kb-adv-heading1658_6d98d7-b0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1658_6d98d7-b0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1658_6d98d7-b0[data-kb-block=\"kb-adv-heading1658_6d98d7-b0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1658_6d98d7-b0 h5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1658_6d98d7-b0\">La malposici\u00f3n dental no s\u00f3lo puede ser un problema est\u00e9tico, sino tambi\u00e9n un problema funcional y de salud bucodental.<\/h3>\n\n\n\n<p>Desde el punto de vista est\u00e9tico cada uno le dar\u00e1 la importancia que crea oportuno, sabiendo que conseguir una buena sonrisa es un motivo suficientemente importante para realizar un tratamiento de ortodoncia. Ahora bien, no todo es mejor est\u00e9tica.<\/p>\n\n\n\n<p>Una buena posici\u00f3n dental comporta una serie de ventajas de tipo funcional y de salud bucodental. La ortodoncia NO tiene edad. En cualquier momento de la vida, es un buen momento para realizar el tratamiento de ortodoncia.<\/p>\n\n\n\n<p>Desde el punto de vista funcional, una buena posici\u00f3n dental puede evitar problemas de la articulaci\u00f3n temporo-mandibular (ATM). Si la articulaci\u00f3n de la mand\u00edbula le duele al abrir y\/o cerrar la boca, uno de los posibles motivos puede ser una malposici\u00f3n de los dientes. Si los dientes no cierran correctamente o cuando hace los movimientos habituales los dientes tienen unos contactos no adecuados, pueden acarrear un dolor, limitaci\u00f3n de apertura\u2026 de la ATM. Adem\u00e1s, esta malposici\u00f3n puede ocasionar unos desgastes en los dientes que pueden, tambi\u00e9n, dar sensibilidad, fracturas, movilidades\u2026 de los dientes.<\/p>\n\n\n\n<p>Otra consecuencia de la malposici\u00f3n dental es la dificultad de tener una buena higiene dental, es decir, si tenemos los dientes mal puestos, tenemos una peor higiene, por lo que aumentan los problemas de sangrado de las enc\u00edas (gingivitis y\/o periodontitis) y los problemas de caries.&nbsp; Peor higiene, peor salud.<\/p>\n\n\n\n<p>La correcci\u00f3n de esta mal posici\u00f3n dental es lo que se llama Ortodoncia. La ortodoncia se puede realizar de diferentes formas: brackets met\u00e1licos, brackets transparentes o alineadores transparentes.<\/p>\n\n\n\n<p>Con las nuevas tecnolog\u00edas podemos corregir esta malposici\u00f3n utilizando unos pl\u00e1sticos muy finos, de quitar y poner, llamados Alineadores Transparentes. Conllevan una ortodoncia m\u00e1s c\u00f3moda para el paciente, una mejor est\u00e9tica, una higiene m\u00e1s f\u00e1cil pero, tambi\u00e9n, un mayor compromiso por parte del paciente, de pon\u00e9rselos todas las horas del d\u00eda, acepto para comer y en el momento de hacer la higiene.<\/p>\n\n\n\n<p>Los brackets met\u00e1licos o transparentes pueden ser m\u00e1s visibles, especialmente los met\u00e1licos, pero no requieren de este compromiso por parte del paciente ya que no se pueden quitar, pero tambi\u00e9n tienen un inconveniente: dificultan la higiene bucal del paciente.<\/p>\n\n\n\n<p>En todos los casos, nuestro equipo de ortodoncistas le explicar\u00e1n las ventajas y desventajas de los distintos tipos de ortodoncia, la mejor ortodoncia para usted.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1658_7ff556-6a > .kt-inside-inner-col,.kadence-column1658_7ff556-6a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1658_7ff556-6a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1658_7ff556-6a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1658_7ff556-6a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1658_7ff556-6a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1658_7ff556-6a{position:relative;}@media all and (max-width: 1024px){.kadence-column1658_7ff556-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1658_7ff556-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1658_7ff556-6a columna--cita\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-senff-sticky-block\" data-topspace=\"24\" data-cfa=\"true\" data-minwidth=\"768\" data-maxwidth=\"1024\" data-pushup=\".faq\" data-zindex=\"1\"><style>.kb-row-layout-id1370_9367ad-32 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1370_9367ad-32 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1370_9367ad-32 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:70px;padding-right:70px;padding-bottom:70px;padding-left:70px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1370_9367ad-32 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1370_9367ad-32 > .kt-row-column-wrap{padding-top:35px;padding-right:35px;padding-bottom:35px;padding-left:35px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1370_9367ad-32 > .kt-row-column-wrap{padding-top:17px;padding-right:17px;padding-bottom:17px;padding-left:17px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1370_9367ad-32 alignnone formulari--cita wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1370_571355-06 > .kt-inside-inner-col,.kadence-column1370_571355-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1370_571355-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1370_571355-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1370_571355-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1370_571355-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1370_571355-06{position:relative;}@media all and (max-width: 1024px){.kadence-column1370_571355-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1370_571355-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1370_571355-06\"><div class=\"kt-inside-inner-col\"><h3 class=\"has-text-align-center h5 wp-block-post-title\">Ortodoncia con brackets y alineadores transparentes<\/h3>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1370_02f68d-f3, .wp-block-kadence-advancedheading.kt-adv-heading1370_02f68d-f3[data-kb-block=\"kb-adv-heading1370_02f68d-f3\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1370_02f68d-f3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1370_02f68d-f3[data-kb-block=\"kb-adv-heading1370_02f68d-f3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1370_02f68d-f3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1370_02f68d-f3[data-kb-block=\"kb-adv-heading1370_02f68d-f3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading1370_02f68d-f3 h5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1370_02f68d-f3\">Pide cita previa<\/h4>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1582-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"1582\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/1658#wpcf7-f1582-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1582\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1582-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p>\t\t<div id=\"cf7md-form\" class=\"cf7md-form\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t<div class=\"mdc-layout-grid__inner\">\n\t\t\t\t\t\t\t\t\t\t\n<\/p>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"nom\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nom\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Nombre<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Correo electr\u00f3nico<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" id=\"telefon\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefon\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Tel\u00e9fono<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"motiu-consulta\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"motiu-consulta\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"motiu-consulta\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Motivo de la consulta<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\n\t\t<div class=\"cf7md-item cf7md-textarea mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone cf7md-textarea-autosize\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"consulta\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"consulta\" aria-required=\"true\" aria-invalid=\"false\" name=\"consulta\"><\/textarea><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--textarea\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Consulta<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\" data-button-style=\"raised\">\n\t\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Pide cita\" \/><br \/>\n\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-accept cf7md-is-wpcf7v5 mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"aceptacio\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"aceptacio\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span><br \/>\n\t\t\t<label class=\"cf7md-accept-label\"><strong>Consiento el tratamiento de mis datos.<\/strong> Cl\u00ednica Dental Oriol Cant\u00f3 tratar\u00e1 tus datos con el fin de responder a tus consultas, dudas o reclamaciones. Puedes ejercer los derechos de acceso, rectificaci\u00f3n, supresi\u00f3n, portabilidad, limitaci\u00f3n y oposici\u00f3n, tal y como le informamos en la nuestra <a href='https:\/\/clinicaoriolcanto.com\/es\/politica-de-privacidad\/' target='_blank'>Pol\u00edtica de Privacidad<\/a>.<\/label>\n\t\t\t<div style=\"display: none;\" class=\"cf7md-checkbox-html\">\n\t\t\t\t<div class=\"mdc-checkbox__background\">\n\t\t\t\t\t<svg class=\"mdc-checkbox__checkmark\" viewBox=\"0 0 24 24\">\n\t\t\t\t\t\t<path class=\"mdc-checkbox__checkmark-path\" fill=\"none\" d=\"M1.73,12.91 8.1,19.28 22.79,4.59\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t\t<div class=\"mdc-checkbox__mixedmark\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/div>\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1658_a38b8e-c3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1658_a38b8e-c3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1658_a38b8e-c3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1658_a38b8e-c3{background-color:#fff7f0;}.kb-row-layout-id1658_a38b8e-c3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1658_a38b8e-c3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1658_a38b8e-c3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1658_a38b8e-c3 alignfull kt-row-has-bg fila--estatic faq wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1658_627526-ab > .kt-inside-inner-col,.kadence-column1658_627526-ab > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1658_627526-ab > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1658_627526-ab > .kt-inside-inner-col{flex-direction:column;}.kadence-column1658_627526-ab > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1658_627526-ab > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1658_627526-ab{position:relative;}@media all and (max-width: 1024px){.kadence-column1658_627526-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1658_627526-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1658_627526-ab\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1658_28e274-a1, .wp-block-kadence-advancedheading.kt-adv-heading1658_28e274-a1[data-kb-block=\"kb-adv-heading1658_28e274-a1\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1658_28e274-a1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1658_28e274-a1[data-kb-block=\"kb-adv-heading1658_28e274-a1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1658_28e274-a1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1658_28e274-a1[data-kb-block=\"kb-adv-heading1658_28e274-a1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1658_28e274-a1 h1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1658_28e274-a1\">Preguntas frecuentes<\/h2>\n\n\n<style>.kb-row-layout-id1658_3f787c-bb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1658_3f787c-bb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1658_3f787c-bb > .kt-row-column-wrap{column-gap:105px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1658_3f787c-bb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1658_3f787c-bb > .kt-row-column-wrap{column-gap:35px;padding-right:20px;padding-left:20px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1658_3f787c-bb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1658_3f787c-bb alignnone container fila--estatic faq--2 grid--full wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1658_014024-24 > .kt-inside-inner-col,.kadence-column1658_014024-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1658_014024-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1658_014024-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1658_014024-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1658_014024-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1658_014024-24{position:relative;}@media all and (max-width: 1024px){.kadence-column1658_014024-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1658_014024-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1658_014024-24\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1658_642e63-cc, .wp-block-kadence-advancedheading.kt-adv-heading1658_642e63-cc[data-kb-block=\"kb-adv-heading1658_642e63-cc\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1658_642e63-cc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1658_642e63-cc[data-kb-block=\"kb-adv-heading1658_642e63-cc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1658_642e63-cc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1658_642e63-cc[data-kb-block=\"kb-adv-heading1658_642e63-cc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1658_642e63-cc h4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1658_642e63-cc\">\u00bfSe debe llevar a los ni\u00f1os al ortodoncista? \u00bfNo es suficiente que lo revise un\/a odont\u00f3logo\/a?<\/h3>\n\n\n\n<p>Lo mejor es realizar una primera visita cuando el ni\u00f1o\/a ya tiene alg\u00fan diente. De esta forma, ya se empieza a familiarizar con el dentista y con el cuidado de sus dientes. Algunas malformaciones dentales y\/o esquel\u00e9ticas ya pueden empezar a tratarse a edades muy tempranas. A partir de los 8 a\u00f1os, cuando ya se han desarrollado los incisivos superiores e inferiores definitivos, la visita es ya muy importante. Esta visita de control puede ayudar a diagnosticar cualquier problema que pudiera surgir y corregirlo de inicio.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1658_eb2f66-cb, .wp-block-kadence-advancedheading.kt-adv-heading1658_eb2f66-cb[data-kb-block=\"kb-adv-heading1658_eb2f66-cb\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1658_eb2f66-cb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1658_eb2f66-cb[data-kb-block=\"kb-adv-heading1658_eb2f66-cb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1658_eb2f66-cb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1658_eb2f66-cb[data-kb-block=\"kb-adv-heading1658_eb2f66-cb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1658_eb2f66-cb h4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1658_eb2f66-cb\">\u00bfCu\u00e1l es la edad ideal para empezar un tratamiento de ortodoncia en ni\u00f1os?<\/h3>\n\n\n\n<p>No existe una edad ideal. Los tratamientos con aparatolog\u00eda removible pueden empezarse a partir de los 8 a\u00f1os m\u00e1s o menos. Los tratamientos con aparatos fijos se pueden utilizar una vez que el ni\u00f1o o ni\u00f1a ya tienen los dientes definitivos.<\/p>\n\n\n\n<p>El objetivo de estos tratamientos es el de mover todos los dientes a su posici\u00f3n correcta, de modo que el mordisco sea el correcto.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1658_b47391-3e > .kt-inside-inner-col,.kadence-column1658_b47391-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1658_b47391-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1658_b47391-3e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1658_b47391-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1658_b47391-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1658_b47391-3e{position:relative;}@media all and (max-width: 1024px){.kadence-column1658_b47391-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1658_b47391-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1658_b47391-3e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1658_9f180e-f3, .wp-block-kadence-advancedheading.kt-adv-heading1658_9f180e-f3[data-kb-block=\"kb-adv-heading1658_9f180e-f3\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1658_9f180e-f3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1658_9f180e-f3[data-kb-block=\"kb-adv-heading1658_9f180e-f3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1658_9f180e-f3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1658_9f180e-f3[data-kb-block=\"kb-adv-heading1658_9f180e-f3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1658_9f180e-f3 h4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1658_9f180e-f3\">\u00bfQu\u00e9 ventaja presentan los alineadores transparentes respecto a los brackets tradicionales?<\/h3>\n\n\n\n<p>Adem\u00e1s de una higiene bucal continua y, en ocasiones mejorada, resulta m\u00e1s f\u00e1cil llevar un estilo de vida activo con alineadores transparentes que con aparatolog\u00eda met\u00e1lica o transparente fija con brackets. El tratamiento de alineadores transparentes consiste en una serie de aligners (alienadores) pr\u00e1cticamente invisibles y extra\u00edbles que se cambian cada dos semanas aproximadamente por un nuevo juego de aligners. Cada uno de ellos se fabrica espec\u00edficamente para tus dientes y s\u00f3lo para tus dientes.<\/p>\n\n\n\n<p>Dado que los aparatos son extra\u00edbles, puedes hacer deporte, tocar instrumentos musicales y, en general, facilitar todas las actividades cotidianas de forma normal. Se deben quitar en el momento de comer, lav\u00e1ndose la boca antes de volver a ponerlos.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1658_f8a9b5-72, .wp-block-kadence-advancedheading.kt-adv-heading1658_f8a9b5-72[data-kb-block=\"kb-adv-heading1658_f8a9b5-72\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1658_f8a9b5-72 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1658_f8a9b5-72[data-kb-block=\"kb-adv-heading1658_f8a9b5-72\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1658_f8a9b5-72 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1658_f8a9b5-72[data-kb-block=\"kb-adv-heading1658_f8a9b5-72\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1658_f8a9b5-72 h4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1658_f8a9b5-72\">\u00bfPueden los adultos llevar ortodoncia?<\/h3>\n\n\n\n<p>No hay edad l\u00edmite para empezar un tratamiento de ortodoncia. Todo momento es bueno para mejorar su salud y est\u00e9tica dental con ortodoncia.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Soluciones de ortodoncia con brackets met\u00e1licos, transparentes o alineadores para una mejor sonrisa y una higiene dental optimizada.<\/p>\n","protected":false},"author":1,"featured_media":365,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-builder.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1658","page","type-page","status-publish","has-post-thumbnail","hentry","post","with-featured-image"],"_links":{"self":[{"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/pages\/1658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/comments?post=1658"}],"version-history":[{"count":3,"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/pages\/1658\/revisions"}],"predecessor-version":[{"id":1905,"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/pages\/1658\/revisions\/1905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/media\/365"}],"wp:attachment":[{"href":"https:\/\/clinicaoriolcanto.com\/es\/wp-json\/wp\/v2\/media?parent=1658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}